{"id":10,"date":"2018-11-01T11:22:16","date_gmt":"2018-11-01T10:22:16","guid":{"rendered":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/widerruf\/"},"modified":"2018-11-01T11:25:10","modified_gmt":"2018-11-01T10:25:10","slug":"widerruf","status":"publish","type":"page","link":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/widerruf\/","title":{"rendered":"Widerruf"},"content":{"rendered":"<p><em>Widerrufsbelehrung<\/em><br \/>\nVerbraucher ist jede nat\u00fcrliche Person, die ein Rechtsgesch\u00e4ft zu Zwecken abschlie\u00dft, die \u00fcberwiegend weder ihrer gewerblichen noch ihrer selbst\u00e4ndigen beruflichen T\u00e4tigkeit zugerechnet werden k\u00f6nnen.<\/p>\n<p><em>Widerrufsrecht<\/em><br \/>\nSie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die Waren in Besitz genommen haben bzw. hat. Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns (Sport G\u00fcrteler GmbH, Siriusstra\u00dfe 2, 85614 Eglharting\/Kirchseeon, Telefon +49 8091 2424, Telefax +49 8091-1372, info@sport-guerteler.de) mittels einer eindeutigen Erkl\u00e4rung (z.B. ein mit der Post versandter Brief, Telefax oder E-Mail) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Sie k\u00f6nnen daf\u00fcr das beigef\u00fcgte Muster-Widerrufsformular verwenden, das jedoch nicht vorgeschrieben ist. Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\n<p><em>Folgen des Widerrufs<\/em><br \/>\nWenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstigste Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrags bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet. Wir k\u00f6nnen die R\u00fcckzahlung verweigern, bis wir die Waren wieder zur\u00fcckerhalten haben oder bis Sie den Nachweis erbracht haben, dass Sie die Waren zur\u00fcckgesandt haben, je nachdem, welches der fr\u00fchere Zeitpunkt ist. Sie haben die Waren unverz\u00fcglich und in jedem Fall sp\u00e4testens binnen vierzehn Tagen ab dem Tag, an dem Sie uns \u00fcber den Widerruf dieses Vertrags unterrichten, an uns zur\u00fcckzusenden oder zu \u00fcbergeben. Die Frist ist gewahrt, wenn Sie die Waren vor Ablauf der Frist von vierzehn Tagen absenden.<br \/>\nSie tragen die unmittelbaren Kosten der R\u00fccksendung der Waren.<br \/>\nSie m\u00fcssen f\u00fcr einen etwaigen Wertverlust der Waren nur aufkommen, wenn dieser Wertverlust auf einen zur Pr\u00fcfung der Beschaffenheit, Eigenschaften und Funktionsweise der Waren nicht notwendigen Umgang mit ihnen zur\u00fcckzuf\u00fchren ist.<\/p>\n<p><em>Muster-Widerrufsformular<\/em><br \/>\n(Wenn Sie den Vertrag widerrufen wollen, dann f\u00fcllen Sie bitte dieses Formular aus und senden Sie es zur\u00fcck.)<br \/>\n&#8211; An Sport G\u00fcrteler GmbH, Siriusstra\u00dfe 2, 85614 Eglharting\/Kirchseeon, Telefon +49 8091 2424, Telefax +49 8091-1372, info@sport-guerteler.de:<br \/>\n&#8211; Hiermit widerrufe(n) ich\/wir (*) den von mir\/uns (*) abgeschlossenen Vertrag \u00fcber den Kauf der folgenden Waren (*)\/ die Erbringung der folgenden Dienstleistung (*)<br \/>\n&#8211; Bestellt am (*)\/erhalten am (*)<br \/>\n&#8211; Name des\/der Verbraucher(s)<br \/>\n&#8211; Anschrift des\/der Verbraucher(s)<br \/>\n&#8211; Unterschrift des\/der Verbraucher(s) (nur bei Mitteilung auf Papier)<br \/>\n&#8211; Datum<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\n(*) Unzutreffendes streichen.<\/p>\n<p><em>Ausschluss bzw. vorzeitiges Erl\u00f6schen des Widerrufsrechts<\/em><br \/>\nDas Widerrufsrecht besteht nicht bei Vertr\u00e4gen<br \/>\nzur Lieferung von Waren, die nicht vorgefertigt sind und f\u00fcr deren Herstellung eine individuelle Auswahl oder Bestimmung durch den Verbraucher ma\u00dfgeblich ist oder die eindeutig auf die pers\u00f6nlichen Bed\u00fcrfnisse des Verbrauchers zugeschnitten sind;<br \/>\nzur Lieferung von Waren, die schnell verderben k\u00f6nnen oder deren Verfallsdatum schnell \u00fcberschritten w\u00fcrde;<br \/>\nzur Lieferung alkoholischer Getr\u00e4nke, deren Preis bei Vertragsschluss vereinbart wurde, die aber fr\u00fchestens 30 Tage nach Vertragsschluss geliefert werden k\u00f6nnen und deren aktueller Wert von Schwankungen auf dem Markt abh\u00e4ngt, auf die der Unternehmer keinen Einfluss hat;<br \/>\nzur Lieferung von Zeitungen, Zeitschriften oder Illustrierten mit Ausnahme von Abonnement-Vertr\u00e4gen.<br \/>\nDas Widerrufsrecht erlischt vorzeitig bei Vertr\u00e4gen<br \/>\nzur Lieferung versiegelter Waren, die aus Gr\u00fcnden des Gesundheitsschutzes oder der Hygiene nicht zur R\u00fcckgabe geeignet sind, wenn ihre Versiegelung nach der Lieferung entfernt wurde;<br \/>\nzur Lieferung von Waren, wenn diese nach der Lieferung auf Grund ihrer Beschaffenheit untrennbar mit anderen G\u00fctern vermischt wurden;<br \/>\nzur Lieferung von Ton- oder Videoaufnahmen oder Computersoftware in einer versiegelten Packung, wenn die Versiegelung nach der Lieferung entfernt wurde.<\/p>\n<p><strong>Widerrufsbelehrung f\u00fcr Verbraucher f\u00fcr einen Vertrag \u00fcber mehrere Waren, die der Verbraucher im Rahmen einer einheitlichen Bestellung bestellt hat und die getrennt geliefert werden<\/strong><\/p>\n<p><em>Widerrufsbelehrung<\/em><br \/>\nVerbraucher ist jede nat\u00fcrliche Person, die ein Rechtsgesch\u00e4ft zu Zwecken abschlie\u00dft, die \u00fcberwiegend weder ihrer gewerblichen noch ihrer selbst\u00e4ndigen beruflichen T\u00e4tigkeit zugerechnet werden k\u00f6nnen.<\/p>\n<p><em>Widerrufsrecht<\/em><br \/>\nSie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die letzte Ware in Besitz genommen haben bzw. hat. Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns (Sport G\u00fcrteler GmbH, Siriusstra\u00dfe 2, 85614 Eglharting\/Kirchseeon, Telefon +49 8091 2424, Telefax +49 8091-1372, info@sport-guerteler.de) mittels einer eindeutigen Erkl\u00e4rung (z.B. ein mit der Post versandter Brief, Telefax oder E-Mail) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Sie k\u00f6nnen daf\u00fcr das beigef\u00fcgte Muster-Widerrufsformular verwenden, das jedoch nicht vorgeschrieben ist. Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\n<p><em>Folgen des Widerrufs<\/em><br \/>\nWenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstigste Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrags bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet. Wir k\u00f6nnen die R\u00fcckzahlung verweigern, bis wir die Waren wieder zur\u00fcckerhalten haben oder bis Sie den Nachweis erbracht haben, dass Sie die Waren zur\u00fcckgesandt haben, je nachdem, welches der fr\u00fchere Zeitpunkt ist. Sie haben die Waren unverz\u00fcglich und in jedem Fall sp\u00e4testens binnen vierzehn Tagen ab dem Tag, an dem Sie uns \u00fcber den Widerruf dieses Vertrags unterrichten, an uns zur\u00fcckzusenden oder zu \u00fcbergeben. Die Frist ist gewahrt, wenn Sie die Waren vor Ablauf der Frist von vierzehn Tagen absenden.<br \/>\nSie tragen die unmittelbaren Kosten der R\u00fccksendung der Waren.<br \/>\nSie m\u00fcssen f\u00fcr einen etwaigen Wertverlust der Waren nur aufkommen, wenn dieser Wertverlust auf einen zur Pr\u00fcfung der Beschaffenheit, Eigenschaften und Funktionsweise der Waren nicht notwendigen Umgang mit ihnen zur\u00fcckzuf\u00fchren ist.<\/p>\n<p><em>Muster-Widerrufsformular<\/em><br \/>\n(Wenn Sie den Vertrag widerrufen wollen, dann f\u00fcllen Sie bitte dieses Formular aus und senden Sie es zur\u00fcck.)<br \/>\n&#8211; An Sport G\u00fcrteler GmbH, Siriusstra\u00dfe 2, 85614 Eglharting\/Kirchseeon, Telefon +49 8091 2424, Telefax +49 8091-1372, info@sport-guerteler.de:<br \/>\n&#8211; Hiermit widerrufe(n) ich\/wir (*) den von mir\/uns (*) abgeschlossenen Vertrag \u00fcber den Kauf der folgenden Waren (*)\/ die Erbringung der folgenden Dienstleistung (*)<br \/>\n&#8211; Bestellt am (*)\/erhalten am (*)<br \/>\n&#8211; Name des\/der Verbraucher(s)<br \/>\n&#8211; Anschrift des\/der Verbraucher(s)<br \/>\n&#8211; Unterschrift des\/der Verbraucher(s) (nur bei Mitteilung auf Papier)<br \/>\n&#8211; Datum<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\n(*) Unzutreffendes streichen.<\/p>\n<p><em>Ausschluss bzw. vorzeitiges Erl\u00f6schen des Widerrufsrechts<br \/>\nDas Widerrufsrecht besteht nicht bei Vertr\u00e4gen<\/em><br \/>\nzur Lieferung von Waren, die nicht vorgefertigt sind und f\u00fcr deren Herstellung eine individuelle Auswahl oder Bestimmung durch den Verbraucher ma\u00dfgeblich ist oder die eindeutig auf die pers\u00f6nlichen Bed\u00fcrfnisse des Verbrauchers zugeschnitten sind;<br \/>\nzur Lieferung von Waren, die schnell verderben k\u00f6nnen oder deren Verfallsdatum schnell \u00fcberschritten w\u00fcrde;<br \/>\nzur Lieferung alkoholischer Getr\u00e4nke, deren Preis bei Vertragsschluss vereinbart wurde, die aber fr\u00fchestens 30 Tage nach Vertragsschluss geliefert werden k\u00f6nnen und deren aktueller Wert von Schwankungen auf dem Markt abh\u00e4ngt, auf die der Unternehmer keinen Einfluss hat;<br \/>\nzur Lieferung von Zeitungen, Zeitschriften oder Illustrierten mit Ausnahme von Abonnement-Vertr\u00e4gen.<br \/>\nDas Widerrufsrecht erlischt vorzeitig bei Vertr\u00e4gen<br \/>\nzur Lieferung versiegelter Waren, die aus Gr\u00fcnden des Gesundheitsschutzes oder der Hygiene nicht zur R\u00fcckgabe geeignet sind, wenn ihre Versiegelung nach der Lieferung entfernt wurde;<br \/>\nzur Lieferung von Waren, wenn diese nach der Lieferung auf Grund ihrer Beschaffenheit untrennbar mit anderen G\u00fctern vermischt wurden;<br \/>\nzur Lieferung von Ton- oder Videoaufnahmen oder Computersoftware in einer versiegelten Packung, wenn die Versiegelung nach der Lieferung entfernt wurde.<\/p>\n<p><strong>Widerrufsbelehrung f\u00fcr Verbraucher f\u00fcr einen Vertrag \u00fcber die Lieferung einer Ware in mehreren Teilleistungen oder St\u00fccken<\/strong><\/p>\n<p><em>Widerrufsbelehrung<\/em><br \/>\nVerbraucher ist jede nat\u00fcrliche Person, die ein Rechtsgesch\u00e4ft zu Zwecken abschlie\u00dft, die \u00fcberwiegend weder ihrer gewerblichen noch ihrer selbst\u00e4ndigen beruflichen T\u00e4tigkeit zugerechnet werden k\u00f6nnen.<\/p>\n<p><em>Widerrufsrecht<\/em><br \/>\nSie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die letzte Teilsendung oder das letzte St\u00fcck in Besitz genommen haben bzw. hat. Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns Sport G\u00fcrteler GmbH, Siriusstra\u00dfe 2, 85614 Eglharting\/Kirchseeon, Telefon +49 8091 2424, Telefax +49 8091-1372, info@sport-guerteler.de) mittels einer eindeutigen Erkl\u00e4rung (z.B. ein mit der Post versandter Brief, Telefax oder E-Mail) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Sie k\u00f6nnen daf\u00fcr das beigef\u00fcgte Muster-Widerrufsformular verwenden, das jedoch nicht vorgeschrieben ist. Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\n<p><em>Folgen des Widerrufs<\/em><br \/>\nWenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstigste Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrags bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet. Wir k\u00f6nnen die R\u00fcckzahlung verweigern, bis wir die Waren wieder zur\u00fcckerhalten haben oder bis Sie den Nachweis erbracht haben, dass Sie die Waren zur\u00fcckgesandt haben, je nachdem, welches der fr\u00fchere Zeitpunkt ist. Sie haben die Waren unverz\u00fcglich und in jedem Fall sp\u00e4testens binnen vierzehn Tagen ab dem Tag, an dem Sie uns \u00fcber den Widerruf dieses Vertrags unterrichten, an uns zur\u00fcckzusenden oder zu \u00fcbergeben. Die Frist ist gewahrt, wenn Sie die Waren vor Ablauf der Frist von vierzehn Tagen absenden.<br \/>\nSie tragen die unmittelbaren Kosten der R\u00fccksendung der Waren.<br \/>\nSie m\u00fcssen f\u00fcr einen etwaigen Wertverlust der Waren nur aufkommen, wenn dieser Wertverlust auf einen zur Pr\u00fcfung der Beschaffenheit, Eigenschaften und Funktionsweise der Waren nicht notwendigen Umgang mit ihnen zur\u00fcckzuf\u00fchren ist.<\/p>\n<p><em>Muster-Widerrufsformular<\/em><br \/>\n(Wenn Sie den Vertrag widerrufen wollen, dann f\u00fcllen Sie bitte dieses Formular aus und senden Sie es zur\u00fcck.)<br \/>\n&#8211; An Sport G\u00fcrteler GmbH, Siriusstra\u00dfe 2, 85614 Eglharting\/Kirchseeon, Telefon +49 8091 2424, Telefax +49 8091-1372, info@sport-guerteler.de:<br \/>\n&#8211; Hiermit widerrufe(n) ich\/wir (*) den von mir\/uns (*) abgeschlossenen Vertrag \u00fcber den Kauf der folgenden Waren (*)\/ die Erbringung der folgenden Dienstleistung (*)<br \/>\n&#8211; Bestellt am (*)\/erhalten am (*)<br \/>\n&#8211; Name des\/der Verbraucher(s)<br \/>\n&#8211; Anschrift des\/der Verbraucher(s)<br \/>\n&#8211; Unterschrift des\/der Verbraucher(s) (nur bei Mitteilung auf Papier)<br \/>\n&#8211; Datum<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\n(*) Unzutreffendes streichen.<\/p>\n<p><em>Ausschluss bzw. vorzeitiges Erl\u00f6schen des Widerrufsrechts<br \/>\nDas Widerrufsrecht besteht nicht bei Vertr\u00e4gen<\/em><br \/>\nzur Lieferung von Waren, die nicht vorgefertigt sind und f\u00fcr deren Herstellung eine individuelle Auswahl oder Bestimmung durch den Verbraucher ma\u00dfgeblich ist oder die eindeutig auf die pers\u00f6nlichen Bed\u00fcrfnisse des Verbrauchers zugeschnitten sind;<br \/>\nzur Lieferung von Waren, die schnell verderben k\u00f6nnen oder deren Verfallsdatum schnell \u00fcberschritten w\u00fcrde;<br \/>\nzur Lieferung alkoholischer Getr\u00e4nke, deren Preis bei Vertragsschluss vereinbart wurde, die aber fr\u00fchestens 30 Tage nach Vertragsschluss geliefert werden k\u00f6nnen und deren aktueller Wert von Schwankungen auf dem Markt abh\u00e4ngt, auf die der Unternehmer keinen Einfluss hat;<br \/>\nzur Lieferung von Zeitungen, Zeitschriften oder Illustrierten mit Ausnahme von Abonnement-Vertr\u00e4gen.<br \/>\nDas Widerrufsrecht erlischt vorzeitig bei Vertr\u00e4gen<br \/>\nzur Lieferung versiegelter Waren, die aus Gr\u00fcnden des Gesundheitsschutzes oder der Hygiene nicht zur R\u00fcckgabe geeignet sind, wenn ihre Versiegelung nach der Lieferung entfernt wurde;<br \/>\nzur Lieferung von Waren, wenn diese nach der Lieferung auf Grund ihrer Beschaffenheit untrennbar mit anderen G\u00fctern vermischt wurden;<br \/>\nzur Lieferung von Ton- oder Videoaufnahmen oder Computersoftware in einer versiegelten Packung, wenn die Versiegelung nach der Lieferung entfernt wurde;<\/p>\n<p><strong>Widerrufsbelehrung f\u00fcr Verbraucher f\u00fcr einen Vertrag zur regelm\u00e4\u00dfigen Lieferung von Waren \u00fcber einen festgelegten Zeitraum hinweg<\/strong><\/p>\n<p><em>Widerrufsbelehrung<\/em><br \/>\nVerbraucher ist jede nat\u00fcrliche Person, die ein Rechtsgesch\u00e4ft zu Zwecken abschlie\u00dft, die \u00fcberwiegend weder ihrer gewerblichen noch ihrer selbst\u00e4ndigen beruflichen T\u00e4tigkeit zugerechnet werden k\u00f6nnen.<\/p>\n<p><em>Widerrufsrecht<\/em><br \/>\nSie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die erste Ware in Besitz genommen haben bzw. hat. Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns (Sport G\u00fcrteler GmbH, Siriusstra\u00dfe 2, 85614 Eglharting\/Kirchseeon, Telefon +49 8091 2424, Telefax +49 8091-1372, info@sport-guerteler.de) mittels einer eindeutigen Erkl\u00e4rung (z.B. ein mit der Post versandter Brief, Telefax oder E-Mail) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Sie k\u00f6nnen daf\u00fcr das beigef\u00fcgte Muster-Widerrufsformular verwenden, das jedoch nicht vorgeschrieben ist. Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\n<p><em>Folgen des Widerrufs<\/em><br \/>\nWenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstigste Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrags bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet. Wir k\u00f6nnen die R\u00fcckzahlung verweigern, bis wir die Waren wieder zur\u00fcckerhalten haben oder bis Sie den Nachweis erbracht haben, dass Sie die Waren zur\u00fcckgesandt haben, je nachdem, welches der fr\u00fchere Zeitpunkt ist. Sie haben die Waren unverz\u00fcglich und in jedem Fall sp\u00e4testens binnen vierzehn Tagen ab dem Tag, an dem Sie uns \u00fcber den Widerruf dieses Vertrags unterrichten, an uns zur\u00fcckzusenden oder zu \u00fcbergeben. Die Frist ist gewahrt, wenn Sie die Waren vor Ablauf der Frist von vierzehn Tagen absenden.<br \/>\nSie tragen die unmittelbaren Kosten der R\u00fccksendung der Waren.<br \/>\nSie m\u00fcssen f\u00fcr einen etwaigen Wertverlust der Waren nur aufkommen, wenn dieser Wertverlust auf einen zur Pr\u00fcfung der Beschaffenheit, Eigenschaften und Funktionsweise der Waren nicht notwendigen Umgang mit ihnen zur\u00fcckzuf\u00fchren ist.<\/p>\n<p><em>Muster-Widerrufsformular<\/em><br \/>\n(Wenn Sie den Vertrag widerrufen wollen, dann f\u00fcllen Sie bitte dieses Formular aus und senden Sie es zur\u00fcck.)<br \/>\n&#8211; An Sport G\u00fcrteler GmbH, Siriusstra\u00dfe 2, 85614 Eglharting\/Kirchseeon, Telefon +49 8091 2424, Telefax +49 8091-1372, info@sport-guerteler.de:<br \/>\n&#8211; Hiermit widerrufe(n) ich\/wir (*) den von mir\/uns (*) abgeschlossenen Vertrag \u00fcber den Kauf der folgenden Waren (*)\/ die Erbringung der folgenden Dienstleistung (*)<br \/>\n&#8211; Bestellt am (*)\/erhalten am (*)<br \/>\n&#8211; Name des\/der Verbraucher(s)<br \/>\n&#8211; Anschrift des\/der Verbraucher(s)<br \/>\n&#8211; Unterschrift des\/der Verbraucher(s) (nur bei Mitteilung auf Papier)<br \/>\n&#8211; Datum<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\n(*) Unzutreffendes streichen<\/p>\n<p><em>Ausschluss bzw. vorzeitiges Erl\u00f6schen des Widerrufsrechts<br \/>\nDas Widerrufsrecht besteht nicht bei Vertr\u00e4gen<\/em><br \/>\nzur Lieferung von Waren, die nicht vorgefertigt sind und f\u00fcr deren Herstellung eine individuelle Auswahl oder Bestimmung durch den Verbraucher ma\u00dfgeblich ist oder die eindeutig auf die pers\u00f6nlichen Bed\u00fcrfnisse des Verbrauchers zugeschnitten sind;<br \/>\nzur Lieferung von Waren, die schnell verderben k\u00f6nnen oder deren Verfallsdatum schnell \u00fcberschritten w\u00fcrde;<br \/>\nzur Lieferung alkoholischer Getr\u00e4nke, deren Preis bei Vertragsschluss vereinbart wurde, die aber fr\u00fchestens 30 Tage nach Vertragsschluss geliefert werden k\u00f6nnen und deren aktueller Wert von Schwankungen auf dem Markt abh\u00e4ngt, auf die der Unternehmer keinen Einfluss hat;<br \/>\nzur Lieferung von Zeitungen, Zeitschriften oder Illustrierten mit Ausnahme von Abonnement-Vertr\u00e4gen.<br \/>\nDas Widerrufsrecht erlischt vorzeitig bei Vertr\u00e4gen<br \/>\nzur Lieferung versiegelter Waren, die aus Gr\u00fcnden des Gesundheitsschutzes oder der Hygiene nicht zur R\u00fcckgabe geeignet sind, wenn ihre Versiegelung nach der Lieferung entfernt wurde;<br \/>\nzur Lieferung von Waren, wenn diese nach der Lieferung auf Grund ihrer Beschaffenheit untrennbar mit anderen G\u00fctern vermischt wurden;<br \/>\nzur Lieferung von Ton- oder Videoaufnahmen oder Computersoftware in einer versiegelten Packung, wenn die Versiegelung nach der Lieferung entfernt wurde.<\/p>\n<p><strong>Widerrufsbelehrung f\u00fcr einen Vertrag \u00fcber die Lieferung von digitalen Inhalten, die nicht auf einem k\u00f6rperlichen Datentr\u00e4ger geliefert werden<\/strong><br \/>\n<em>Widerrufsbelehrung<\/em><br \/>\nVerbraucher ist jede nat\u00fcrliche Person, die ein Rechtsgesch\u00e4ft zu Zwecken abschlie\u00dft, die \u00fcberwiegend weder ihrer gewerblichen noch ihrer selbst\u00e4ndigen beruflichen T\u00e4tigkeit zugerechnet werden k\u00f6nnen.<\/p>\n<p><em>Widerrufsrecht<\/em><br \/>\nSie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag des Vertragsschlusses. Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns (Sport G\u00fcrteler GmbH, Siriusstra\u00dfe 2, 85614 Eglharting\/Kirchseeon, Telefon +49 8091 2424, Telefax +49 8091-1372, info@sport-guerteler.de) mittels einer eindeutigen Erkl\u00e4rung (z.B. ein mit der Post versandter Brief, Telefax oder E-Mail) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Sie k\u00f6nnen daf\u00fcr das beigef\u00fcgte Muster-Widerrufsformular verwenden, das jedoch nicht vorgeschrieben ist. Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\n<p><em>Folgen des Widerrufs<\/em><br \/>\nWenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstigste Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrags bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet.<\/p>\n<p><em>Muster-Widerrufsformular<\/em><br \/>\n(Wenn Sie den Vertrag widerrufen wollen, dann f\u00fcllen Sie bitte dieses Formular aus und senden Sie es zur\u00fcck.)<br \/>\n&#8211; An Sport G\u00fcrteler GmbH, Siriusstra\u00dfe 2, 85614 Eglharting\/Kirchseeon, Telefon +49 8091 2424, Telefax +49 8091-1372, info@sport-guerteler.de:<br \/>\n&#8211; Hiermit widerrufe(n) ich\/wir (*) den von mir\/uns (*) abgeschlossenen Vertrag \u00fcber den Kauf der folgenden Waren (*)\/ die Erbringung der folgenden Dienstleistung (*)<br \/>\n&#8211; Bestellt am (*)\/erhalten am (*)<br \/>\n&#8211; Name des\/der Verbraucher(s)<br \/>\n&#8211; Anschrift des\/der Verbraucher(s)<br \/>\n&#8211; Unterschrift des\/der Verbraucher(s) (nur bei Mitteilung auf Papier)<br \/>\n&#8211; Datum<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\n(*) Unzutreffendes streichen.<\/p>\n<p><em>Ausschluss bzw. vorzeitiges Erl\u00f6schen des Widerrufsrechts<\/em><br \/>\nDas Widerrufsrecht besteht nicht bei Vertr\u00e4gen zur Lieferung von digitalen Inhalten, die nicht vorgefertigt sind und f\u00fcr deren Herstellung eine individuelle Auswahl oder Bestimmung durch den Verbraucher ma\u00dfgeblich ist oder die eindeutig auf die pers\u00f6nlichen Bed\u00fcrfnisse des Verbrauchers zugeschnitten sind.<br \/>\nDas Widerrufsrecht erlischt vorzeitig, wenn wir mit der Ausf\u00fchrung des Vertrages erst begonnen haben, nachdem Sie dazu Ihre ausdr\u00fcckliche Zustimmung gegeben und gleichzeitig Ihre Kenntnis davon best\u00e4tigt haben, dass Sie Ihr Widerrufsrecht mit Beginn der Vertragserf\u00fcllung unsererseits verlieren. Wir weisen darauf hin, dass wir den Vertragsschluss von der vorgenannten Zustimmung und Best\u00e4tigung abh\u00e4ngig machen k\u00f6nnen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Widerrufsbelehrung Verbraucher ist jede nat\u00fcrliche Person, die ein Rechtsgesch\u00e4ft zu Zwecken abschlie\u00dft, die \u00fcberwiegend weder ihrer gewerblichen noch ihrer selbst\u00e4ndigen beruflichen T\u00e4tigkeit zugerechnet werden k\u00f6nnen. Widerrufsrecht Sie haben das Recht,<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Widerruf - SV Hohenlinden<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.teamprofi.de\/sv-hohenlinden\/widerruf\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Widerruf - SV Hohenlinden\" \/>\n<meta property=\"og:description\" content=\"Widerrufsbelehrung Verbraucher ist jede nat\u00fcrliche Person, die ein Rechtsgesch\u00e4ft zu Zwecken abschlie\u00dft, die \u00fcberwiegend weder ihrer gewerblichen noch ihrer selbst\u00e4ndigen beruflichen T\u00e4tigkeit zugerechnet werden k\u00f6nnen. Widerrufsrecht Sie haben das Recht,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.teamprofi.de\/sv-hohenlinden\/widerruf\/\" \/>\n<meta property=\"og:site_name\" content=\"SV Hohenlinden\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-01T10:25:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"17\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.teamprofi.de\\\/sv-hohenlinden\\\/widerruf\\\/\",\"url\":\"https:\\\/\\\/www.teamprofi.de\\\/sv-hohenlinden\\\/widerruf\\\/\",\"name\":\"Widerruf - SV Hohenlinden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.teamprofi.de\\\/sv-hohenlinden\\\/#website\"},\"datePublished\":\"2018-11-01T10:22:16+00:00\",\"dateModified\":\"2018-11-01T10:25:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.teamprofi.de\\\/sv-hohenlinden\\\/widerruf\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.teamprofi.de\\\/sv-hohenlinden\\\/widerruf\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.teamprofi.de\\\/sv-hohenlinden\\\/widerruf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.teamprofi.de\\\/sv-hohenlinden\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Widerruf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.teamprofi.de\\\/sv-hohenlinden\\\/#website\",\"url\":\"https:\\\/\\\/www.teamprofi.de\\\/sv-hohenlinden\\\/\",\"name\":\"SV Hohenlinden\",\"description\":\"Vereins-Shop Sport G\u00fcrteler\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.teamprofi.de\\\/sv-hohenlinden\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Widerruf - SV Hohenlinden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/widerruf\/","og_locale":"de_DE","og_type":"article","og_title":"Widerruf - SV Hohenlinden","og_description":"Widerrufsbelehrung Verbraucher ist jede nat\u00fcrliche Person, die ein Rechtsgesch\u00e4ft zu Zwecken abschlie\u00dft, die \u00fcberwiegend weder ihrer gewerblichen noch ihrer selbst\u00e4ndigen beruflichen T\u00e4tigkeit zugerechnet werden k\u00f6nnen. Widerrufsrecht Sie haben das Recht,","og_url":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/widerruf\/","og_site_name":"SV Hohenlinden","article_modified_time":"2018-11-01T10:25:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"17\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/widerruf\/","url":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/widerruf\/","name":"Widerruf - SV Hohenlinden","isPartOf":{"@id":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/#website"},"datePublished":"2018-11-01T10:22:16+00:00","dateModified":"2018-11-01T10:25:10+00:00","breadcrumb":{"@id":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/widerruf\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.teamprofi.de\/sv-hohenlinden\/widerruf\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/widerruf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/"},{"@type":"ListItem","position":2,"name":"Widerruf"}]},{"@type":"WebSite","@id":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/#website","url":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/","name":"SV Hohenlinden","description":"Vereins-Shop Sport G\u00fcrteler","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":1,"href":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":21,"href":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/wp-json\/wp\/v2\/pages\/10\/revisions\/21"}],"wp:attachment":[{"href":"https:\/\/www.teamprofi.de\/sv-hohenlinden\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}