{"id":15,"date":"2022-05-18T14:49:45","date_gmt":"2022-05-18T12:49:45","guid":{"rendered":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/versand__lieferung\/"},"modified":"2022-05-18T15:08:23","modified_gmt":"2022-05-18T13:08:23","slug":"versand__lieferung","status":"publish","type":"page","link":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/versand__lieferung\/","title":{"rendered":"Versand &#038; Lieferung"},"content":{"rendered":"<p><strong>Preise, Versandkosten und Lieferinformationen<\/strong><\/p>\n<p>Die auf den Produktseiten genannten Preise enthalten die gesetzliche Mehrwertsteuer und sonstige Preisbestandteile.<\/p>\n<p>Wir liefern nach R\u00fccksprache die Vereine insbesondere bei Sammelbestellungen kostenfrei. Einzelbestellungen bitten wir im Gesch\u00e4ft zu den \u00d6ffnungzeiten abzuholen. Sie erhalten bei Fertigstellung der Individualsierung bzw. bei Fertigstellung des Auftrages eine Benachrichtigung.<\/p>\n<p>Ansonsten berechnen wir zus\u00e4tzlich zu den angegebenen Preisen berechnen wir f\u00fcr die Lieferung innerhalb Deutschlands 6,90 Euro pro Bestellung. Die Versandkosten werden Ihnen im Warenkorbsystem und auf der Bestellseite nochmals deutlich mitgeteilt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Preise, Versandkosten und Lieferinformationen Die auf den Produktseiten genannten Preise enthalten die gesetzliche Mehrwertsteuer und sonstige Preisbestandteile. Wir liefern nach R\u00fccksprache die Vereine insbesondere bei Sammelbestellungen kostenfrei. Einzelbestellungen bitten wir<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-15","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Versand &amp; Lieferung - Gymnasium Kirchseeon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/versand__lieferung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Versand &amp; Lieferung - Gymnasium Kirchseeon\" \/>\n<meta property=\"og:description\" content=\"Preise, Versandkosten und Lieferinformationen Die auf den Produktseiten genannten Preise enthalten die gesetzliche Mehrwertsteuer und sonstige Preisbestandteile. Wir liefern nach R\u00fccksprache die Vereine insbesondere bei Sammelbestellungen kostenfrei. Einzelbestellungen bitten wir\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/versand__lieferung\/\" \/>\n<meta property=\"og:site_name\" content=\"Gymnasium Kirchseeon\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-18T13:08:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.teamprofi.de\\\/gymnasium-kirchseeon\\\/versand__lieferung\\\/\",\"url\":\"https:\\\/\\\/www.teamprofi.de\\\/gymnasium-kirchseeon\\\/versand__lieferung\\\/\",\"name\":\"Versand & Lieferung - Gymnasium Kirchseeon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.teamprofi.de\\\/gymnasium-kirchseeon\\\/#website\"},\"datePublished\":\"2022-05-18T12:49:45+00:00\",\"dateModified\":\"2022-05-18T13:08:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.teamprofi.de\\\/gymnasium-kirchseeon\\\/versand__lieferung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.teamprofi.de\\\/gymnasium-kirchseeon\\\/versand__lieferung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.teamprofi.de\\\/gymnasium-kirchseeon\\\/versand__lieferung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.teamprofi.de\\\/gymnasium-kirchseeon\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Versand &#038; Lieferung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.teamprofi.de\\\/gymnasium-kirchseeon\\\/#website\",\"url\":\"https:\\\/\\\/www.teamprofi.de\\\/gymnasium-kirchseeon\\\/\",\"name\":\"Gymnasium Kirchseeon\",\"description\":\"Eine weitere Vereins Shops - Sport G\u00fcrteler Website\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.teamprofi.de\\\/gymnasium-kirchseeon\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Versand & Lieferung - Gymnasium Kirchseeon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/versand__lieferung\/","og_locale":"de_DE","og_type":"article","og_title":"Versand & Lieferung - Gymnasium Kirchseeon","og_description":"Preise, Versandkosten und Lieferinformationen Die auf den Produktseiten genannten Preise enthalten die gesetzliche Mehrwertsteuer und sonstige Preisbestandteile. Wir liefern nach R\u00fccksprache die Vereine insbesondere bei Sammelbestellungen kostenfrei. Einzelbestellungen bitten wir","og_url":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/versand__lieferung\/","og_site_name":"Gymnasium Kirchseeon","article_modified_time":"2022-05-18T13:08:23+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/versand__lieferung\/","url":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/versand__lieferung\/","name":"Versand & Lieferung - Gymnasium Kirchseeon","isPartOf":{"@id":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/#website"},"datePublished":"2022-05-18T12:49:45+00:00","dateModified":"2022-05-18T13:08:23+00:00","breadcrumb":{"@id":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/versand__lieferung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/versand__lieferung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/versand__lieferung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/"},{"@type":"ListItem","position":2,"name":"Versand &#038; Lieferung"}]},{"@type":"WebSite","@id":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/#website","url":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/","name":"Gymnasium Kirchseeon","description":"Eine weitere Vereins Shops - Sport G\u00fcrteler Website","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/wp-json\/wp\/v2\/pages\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":1,"href":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/wp-json\/wp\/v2\/pages\/15\/revisions"}],"predecessor-version":[{"id":38,"href":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/wp-json\/wp\/v2\/pages\/15\/revisions\/38"}],"wp:attachment":[{"href":"https:\/\/www.teamprofi.de\/gymnasium-kirchseeon\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}